{"id":26045,"date":"2023-03-27T08:30:00","date_gmt":"2023-03-27T06:30:00","guid":{"rendered":"https:\/\/www.freelancermap.com\/blog\/?p=26045"},"modified":"2023-06-07T09:34:23","modified_gmt":"2023-06-07T07:34:23","slug":"que-hace-analista-de-riesgos","status":"publish","type":"post","link":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/","title":{"rendered":"\u00bfQu\u00e9 hace un Analista de Riesgos?"},"content":{"rendered":"\n<p><strong>Los analistas de riesgos son los responsables de identificar las oportunidades y amenazas para una organizaci\u00f3n, en m\u00faltiples \u00e1mbitos de aplicaci\u00f3n. Adicionalmente, definen estrategias y planes de gesti\u00f3n y prevenci\u00f3n de riesgos. \u00bfQu\u00e9 hace el analista de riesgos?<\/strong><\/p>\n\n\n<div class=\"mks_col \">\n<div class=\"mks_one_third \"><div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000a1c;border-radius:3px;\"><div class=\"su-box-title\" style=\"background-color:#2c3d4f;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Visi\u00f3n del puesto<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><span style=\"color: #000000\"><a style=\"color: #000000\" href=\"#Intro\">Analisis y tipos de riesgo<\/a><\/span><br \/><span style=\"color: #000000\"><a style=\"color: #000000\" href=\"#Funciones\">Funciones<\/a><\/span><br \/><span style=\"color: #000000\"><a style=\"color: #000000\" href=\"#Habilidades\">Habilidades<\/a><\/span><br \/><span style=\"color: #000000\"><a style=\"color: #000000\" href=\"#Formacion\">Educaci\u00f3n<\/a><\/span><br \/><span style=\"color: #000000\"><a style=\"color: #000000\" href=\"#Salario\">Salario<\/a><\/span><\/div><\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Intro\">Analisis de Riesgos y Tipos de Riesgo<\/h2>\n\n\n\n<p>A pesar de que la <strong>gesti\u00f3n de riesgos<\/strong> nace como una pr\u00e1ctica empresarial dentro del sector financiero, en la actualidad las empresas de casi todos los sectores industriales emplean analistas de riesgos.&nbsp;<\/p>\n\n\n\n<p>El prop\u00f3sito de esta disciplina es <strong>analizar, prevenir y mitigar los riesgos <\/strong>relacionados con la operaci\u00f3n y los resultados del negocio, para facilitar y sustentar el <strong>direccionamiento estrat\u00e9gico<\/strong> de la empresa.<\/p>\n\n\n\n<p>En este sentido, un <strong>Analista de Riesgos<\/strong> se encarga de <strong>establecer, mantener y mejorar&nbsp; los sistemas de gesti\u00f3n de riesgos <\/strong>de una empresa, desde su an\u00e1lisis hasta su prevenci\u00f3n o mitigaci\u00f3n, seg\u00fan corresponda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"960\" height=\"720\" data-src=\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-un-analista-de-riesgos.png\" alt=\"Resumen del trabajo del Analista de Riesgos\" class=\"wp-image-26059 lazyload\" data-srcset=\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-un-analista-de-riesgos.png 960w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-un-analista-de-riesgos-300x225.png 300w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-un-analista-de-riesgos-768x576.png 768w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-un-analista-de-riesgos-720x540.png 720w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-un-analista-de-riesgos-580x435.png 580w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-un-analista-de-riesgos-320x240.png 320w\" data-sizes=\"(max-width: 960px) 100vw, 960px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 960px; --smush-placeholder-aspect-ratio: 960\/720;\" \/><figcaption class=\"wp-element-caption\">El perfil del analista de riesgos<\/figcaption><\/figure>\n\n\n\n<p>En general, <strong>el an\u00e1lisis de riesgos <\/strong>puede realizarse respecto a la <strong> gesti\u00f3n de calidad<\/strong>, as\u00ed como a los aspectos <strong>financieros, jur\u00eddicos, tecnol\u00f3gicos y de salud laboral<\/strong>, entre otros. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tipos de Riesgos Empresariales<\/h3>\n\n\n\n<p>Aunque es com\u00fan que las organizaciones vean el riesgo con recelo, las actualizaciones m\u00e1s recientes de las normas de calidad y de gesti\u00f3n de riesgos han ampliado su definici\u00f3n del riesgo, <a rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\" href=\"https:\/\/web.isolucion.com.co\/iso-31000-2018-fundamentos-de-gestion-de-riesgos\/\" target=\"_blank\">entendi\u00e9ndolo como el efecto de la incertidumbre sobre los objetivos<\/a>. <\/p>\n\n\n\n<p>Esto implica, que la <strong>gesti\u00f3n de riesgos<\/strong> en la actualidad busca <strong>identificar y gestionar oportunidades de crecimiento<\/strong>, complementariamente con la gesti\u00f3n de amenazas para el negocio.<\/p>\n\n\n\n<p>La formaci\u00f3n y experiencia necesaria para desempe\u00f1ar el rol de Analista de Riesgos depende directamente del \u00e1mbito donde se originan los riesgos, dentro o fuera de la empresa. <\/p>\n\n\n\n<p>A continuaci\u00f3n, mostramos algunos ejemplos de los <strong>riesgos m\u00e1s comunes que enfrentan los Analistas de Riesgos<\/strong> en diferentes tipos de organizaciones:<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Riesgos Externos<\/strong><\/p>\n\n\n\n<p>Los <strong>riesgos externos<\/strong> est\u00e1n relacionados con el <strong>entorno local e internacional<\/strong> de la empresa. En particular, son muy relevantes los factores econ\u00f3micos, pol\u00edticos, sociales y ambientales, tales como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inflaci\u00f3n<\/li>\n\n\n\n<li>Riesgo pa\u00eds<\/li>\n\n\n\n<li>Desastres naturales<\/li>\n\n\n\n<li>Inestabilidad pol\u00edtica<\/li>\n\n\n\n<li>Descontento social<\/li>\n<\/ul>\n\n\n\n<p>Cada uno de estos aspectos, dependiendo del sector industrial, implican informaci\u00f3n relevante para la estrategia empresarial. Los mismos son pertinentes tanto para la definici\u00f3n de planes, como para el establecimiento de acciones de contingencia. Por esta raz\u00f3n, la <strong>prevenci\u00f3n es un componente esencial de la gesti\u00f3n de riesgos<\/strong>.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Riesgos internos<\/strong><\/p>\n\n\n\n<p>Los <strong>riesgos internos<\/strong> est\u00e1n relacionados con la <strong>gesti\u00f3n de la empresa<\/strong>, tanto de los procesos como de sus resultados. Este tipo de riesgos suelen requerir una formaci\u00f3n previa en el \u00e1mbito de aplicaci\u00f3n, a diferencia de los riesgos externos, vinculados con la gesti\u00f3n de riesgos tradicional. <\/p>\n\n\n\n<p>Algunos ejemplos de riesgos internos son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Financieros<\/li>\n\n\n\n<li>Comerciales<\/li>\n\n\n\n<li>Tecnol\u00f3gicos<\/li>\n\n\n\n<li>Jur\u00eddicos<\/li>\n\n\n\n<li>Salud y seguridad laboral<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:18px\"><strong>\u00bfNecesitas un Analista de Riesgos para tu empresa?<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"su-button-center\"><a href=\"https:\/\/www.freelancermap.com\/app\/projekt\/form\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#FFFFFF;background-color:#41c0eb;border-color:#349abc;border-radius:10px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:7px 20px;font-size:16px;line-height:24px;border-color:#7ad3f1;border-radius:10px;text-shadow:none\"><i class=\"sui sui-pencil-square-o\" style=\"font-size:16px;color:#FFFFFF\"><\/i> Publica tu proyecto gratis<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"su-button-center\"><a href=\"https:\/\/www.freelancermap.com\/freelancers-directory.html?qall=risk+management&#038;profisuche=1\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#FFFFFF;background-color:#41c0eb;border-color:#349abc;border-radius:10px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:7px 20px;font-size:16px;line-height:24px;border-color:#7ad3f1;border-radius:10px;text-shadow:none\"><i class=\"sui sui-search\" style=\"font-size:16px;color:#FFFFFF\"><\/i> Analistas de Riesgos<br \/>\n<\/span><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Funciones\">\u00bfCu\u00e1les son las responsabilidades de un Analista de Riesgos?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"960\" height=\"720\" data-src=\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-funciones.png\" alt=\"Lista de responsabilidades del analista de riesgos\" class=\"wp-image-26060 lazyload\" data-srcset=\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-funciones.png 960w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-funciones-300x225.png 300w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-funciones-768x576.png 768w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-funciones-720x540.png 720w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-funciones-580x435.png 580w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-funciones-320x240.png 320w\" data-sizes=\"(max-width: 960px) 100vw, 960px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 960px; --smush-placeholder-aspect-ratio: 960\/720;\" \/><figcaption class=\"wp-element-caption\">Listado de funciones y tareas<\/figcaption><\/figure>\n\n\n\n<p>Las <strong>responsabilidades del Analista de Riesgos <\/strong>var\u00edan de acuerdo a la industria y tipo de riesgo en el que se especializa. En general, los analistas de riesgos recogen y analizan informaci\u00f3n para identificar los riesgos internos y externos. Esto les permite definir el perfil de riesgo, junto con los planes de gesti\u00f3n y estrategias para mitigar y capitalizar los mismos<\/p>\n\n\n\n<p>En funci\u00f3n de los resultados del diagn\u00f3stico, el <strong>Analista de Riesgos<\/strong> eval\u00faa las pol\u00edticas, normas y procedimientos empresariales&nbsp; para verificar el estado de los <strong>m\u00e9todos de gesti\u00f3n de riesgos aplicadas<\/strong> y las brechas correspondientes.<\/p>\n\n\n\n<p>Con base en el <strong>an\u00e1lisis de riesgos<\/strong>, una buena parte de los mismos se pueden mitigar, evitar o eliminar. Sin embargo, dado que la <strong>gesti\u00f3n de riesgos trata con la incertidumbre<\/strong>, es imposible evitar los riesgos del negocio completo.<\/p>\n\n\n\n<p>En estos casos, el <strong>Analista de Riesgos<\/strong> debe establecer recomendaciones para definir el apetito del riesgo de la compa\u00f1\u00eda, en un trabajo cercano con el equipo directivo. <\/p>\n\n\n\n<p>Seg\u00fan sea el caso, se gu\u00eda por las<strong> regulaciones locales e internacionales<\/strong> correspondientes, algo muy com\u00fan en los sectores altamente regulados como el sector financiero y la industria farmac\u00e9utica, por ejemplo.<\/p>\n\n\n\n<p><strong>Tareas y responsabilidades del Analista de Riesgos<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>An\u00e1lisis de riesgos internos y externos<\/li>\n\n\n\n<li>Evaluaci\u00f3n de las pol\u00edticas, normas y procedimientos de la compa\u00f1\u00eda, dentro de su alcance<\/li>\n\n\n\n<li>Diagn\u00f3stico de los m\u00e9todos de gesti\u00f3n de riesgos en funcionamiento<\/li>\n\n\n\n<li>Formulaci\u00f3n de estrategias y planes de gesti\u00f3n de riesgos<\/li>\n\n\n\n<li>Documentaci\u00f3n de cambios en la gesti\u00f3n de riesgos<\/li>\n\n\n\n<li>Proponer recomendaciones para la definici\u00f3n de estrategias de negocio y planes de contingencia y\/o de emergencia, seg\u00fan sea el caso<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Habilidades\">Habilidades y Conocimientos<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"960\" height=\"720\" data-src=\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-habilidades.png\" alt=\"Habilidades y conocimientos necesarios para un analista de riesgos\" class=\"wp-image-26061 lazyload\" data-srcset=\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-habilidades.png 960w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-habilidades-300x225.png 300w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-habilidades-768x576.png 768w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-habilidades-720x540.png 720w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-habilidades-580x435.png 580w, https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/analista-de-riesgos-habilidades-320x240.png 320w\" data-sizes=\"(max-width: 960px) 100vw, 960px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 960px; --smush-placeholder-aspect-ratio: 960\/720;\" \/><figcaption class=\"wp-element-caption\">Listado de habilidades y conocimientos<\/figcaption><\/figure>\n\n\n\n<p>En cualquier \u00e1mbito e industria, la gesti\u00f3n de riesgos requiere un <strong>pensamiento anal\u00edtico<\/strong> sobresaliente para comprender conceptos complejos y detectar eventos emergentes oportunamente. <\/p>\n\n\n\n<p>La mayor\u00eda de los analistas de riesgos utilizan frecuentemente <strong>conocimientos matem\u00e1ticos avanzados<\/strong>, con la excepci\u00f3n de los m\u00e1s especializados en aspectos jur\u00eddicos, de seguridad y salud laboral, donde la formaci\u00f3n acad\u00e9mica previa en Derecho y\/o Ergonom\u00eda, son de mayor relevancia.<\/p>\n\n\n\n<p>En t\u00e9rminos transversales, un analista de riesgos requiere habilidades de <strong>comunicaci\u00f3n asertiva<\/strong>, para transmitir la relevancia y seriedad objetiva de sus hallazgos y recomendaciones, as\u00ed como una <strong>\u00e9tica profesional impecable<\/strong>.<\/p>\n\n\n\n<p>Tambi\u00e9n, un Analista de Riesgos siempre debe trabajar con <strong>minuciosidad y atenci\u00f3n al detalle<\/strong>, cuidando la precisi\u00f3n de la informaci\u00f3n. <\/p>\n\n\n\n<p>Normalmente, un Analista de Riesgos identifica algunas oportunidades y amenazas de forma anticipada, pero en muchos casos tendr\u00e1 que actuar bajo presi\u00f3n, debido a la volatilidad del entorno, que cada vez es m\u00e1s dif\u00edcil de predecir. Por esto, es muy importante la <strong>capacidad de trabajo bajo presi\u00f3n<\/strong>, para este puesto.&nbsp;<\/p>\n\n\n\n<p>Finalmente, es com\u00fan que un analista de riesgos tenga dominio de las <strong>normativas y est\u00e1ndares de gesti\u00f3n de riesgos <\/strong>que regulan la industria en la que se desempe\u00f1a, as\u00ed como de los riesgos espec\u00edficos que gestiona.<\/p>\n\n\n\n<p>Finalmente, es com\u00fan que un analista de riesgos tenga dominio de las <strong>normativas y est\u00e1ndares de gesti\u00f3n de riesgos <\/strong>que regulan la industria en la que se desempe\u00f1a, as\u00ed como de los riesgos espec\u00edficos que gestiona.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 conocimientos necesita el analista de riesgos?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Experiencia en gesti\u00f3n de proyectos <\/li>\n\n\n\n<li>Pensamiento anal\u00edtico y comprensi\u00f3n matem\u00e1tica<\/li>\n\n\n\n<li>Buenas habilidades de presentaci\u00f3n y comunicaci\u00f3n<\/li>\n\n\n\n<li>Precisi\u00f3n y paciencia<\/li>\n\n\n\n<li>Capacidad para trabajar bajo estr\u00e9s y tomar decisiones r\u00e1pidas<\/li>\n\n\n\n<li>Disciplina enfocada y capacidad de concentraci\u00f3n<\/li>\n\n\n\n<li>Conocimiento de la industria en el que la empresa opera, por ejemplo, seguros, energ\u00eda, comercio minorista<\/li>\n\n\n\n<li>Valorable: Ingl\u00e9s, certificaciones de gesti\u00f3n de riesgo tecnol\u00f3gico y gesti\u00f3n IT<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:18px\"><strong>\u00bfEres un Analista de Gesti\u00f3n de Riesgos y buscas nuevos retos?<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"su-button-center\"><a href=\"https:\/\/www.freelancermap.com\/it-projects.html?pq=risk+management&#038;profisuche=1\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#FFFFFF;background-color:#41c0eb;border-color:#349abc;border-radius:10px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:7px 20px;font-size:16px;line-height:24px;border-color:#7ad3f1;border-radius:10px;text-shadow:none\"><i class=\"sui sui-pencil-square-o\" style=\"font-size:16px;color:#FFFFFF\"><\/i> Trabajos en Analisis de  Riesgos<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"su-button-center\"><a href=\"https:\/\/www.freelancermap.com\/registration\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#FFFFFF;background-color:#41c0eb;border-color:#349abc;border-radius:10px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:7px 20px;font-size:16px;line-height:24px;border-color:#7ad3f1;border-radius:10px;text-shadow:none\"><i class=\"sui sui-search\" style=\"font-size:16px;color:#FFFFFF\"><\/i> Carga tu perfil de experto (gratis)<br \/>\n<\/span><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Formacion\">Educaci\u00f3n y formaci\u00f3n<\/h2>\n\n\n\n<p>Dependiendo de la industria y del alcance de la posici\u00f3n, <strong>para trabajar como Analista de Riesgos <\/strong>se puede contar con diversos tipos de formaci\u00f3n acad\u00e9mica. Sin embargo, es indispensable que tenga un conocimiento profundo de su sector econ\u00f3mico y de la empresa, en particular.<\/p>\n\n\n\n<p>Los puestos en el <strong>Sector Financiero <\/strong>exigen formaci\u00f3n en <strong>Matem\u00e1ticas, Finanzas, Actuar\u00eda y aceptan la aplicaci\u00f3n de Ingenieros<\/strong>, toda vez que demuestren destrezas num\u00e9ricas y de an\u00e1lisis destacados.<\/p>\n\n\n\n<p>En el caso de los puestos especializados, de mayor crecimiento reciente, en el <strong>\u00e1mbito tecnol\u00f3gico<\/strong>, las empresas buscan Analistas de Riesgos con conocimientos en auditor\u00eda de sistemas, certificaciones en <strong>Seguridad Inform\u00e1tica, Ethical Hacking, as\u00ed como tecnolog\u00edas, est\u00e1ndares y protocolos para la mitigaci\u00f3n de riesgos inform\u00e1ticos<\/strong>.<\/p>\n\n\n\n<p>Algunas <strong>certificaciones en gesti\u00f3n de riesgos altamente valoradas <\/strong>en el mercado son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ITIL<\/li>\n\n\n\n<li><a rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\" href=\"https:\/\/www.pmi.org\/certifications\/risk-management-rmp\" target=\"_blank\">PMI &#8211; RMP &#8211;  Profesional en Gesti\u00f3n de Riesgos<\/a><\/li>\n\n\n\n<li><em>Certificaciones de gesti\u00f3n de riesgo tecnol\u00f3gico:<\/em>\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.isaca.org\/credentialing\/crisc\">CRISC &#8211; Certificaci\u00f3n en Sistemas de Control de Sistemas de Informaci\u00f3n y Riesgos &#8211; ISACA<\/a><\/li>\n\n\n\n<li>CISA &#8211; Certified Information Systems Auditor<\/li>\n\n\n\n<li>CSX &#8211; Cybersecurity<\/li>\n\n\n\n<li>CISM &#8211; Certified Information Security Manager<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Salario\">Salario de un Analista de Riesgos<\/h2>\n\n\n\n<p>El rango salarial de un <strong>Analista de Riesgos<\/strong> en Estados unidos es de entre <strong>$57,000<\/strong> para perfiles junior y <strong>$102,000<\/strong> para profesionales s\u00e9nior. $75,000 es el promedio anual.<\/p>\n\n\n\n<p>El monto final depende de diferentes factores como el grado acad\u00e9mico, la formaci\u00f3n continua, la experiencia profesional y\/o el tama\u00f1o de la compa\u00f1\u00eda.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1nto cobra un analista de riesgos?<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Salario EE.UU<\/td><td class=\"has-text-align-center\" data-align=\"center\">$57,000 &#8211; 102,000<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Salario Alemania<\/td><td class=\"has-text-align-center\" data-align=\"center\"> \u20ac26,000 &#8211; 57,000<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Salario Espa\u00f1a<\/td><td class=\"has-text-align-center\" data-align=\"center\"> \u20ac25,000 &#8211; 51,000<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>\u00bfY un analista de riesgos freelance?<\/strong><\/p>\n\n\n\n<!--\n    Use the <style> below to style the box.\n\n    This <style> should ideally be placed inside <head><\/head>.\n      If that is not possible, keep it above the box itself.\n\n    If you use the box inside a container, that already limits the width,\n      set \"width: 100%\" inside #fm-hourly-rate-box.\n      This is necessary, if you like the box to be responsive.\n-->\n<style>\n    #fm-hourly-rate-box {\n        margin: auto;\n        width: 100%;\n        padding: 24px;\n        background: white;\n        border-radius: 10px;\n        box-shadow: 2px 4px 20px 0 rgb(90 90 90 \/ 16%);\n        text-align: center;\n        line-hight: 1.5\n    }\n\t   \n\t#fm-hourly-rate-box .fm-hourly-rate-rate {\n        font-size: 30px;\n        font-weight: bold;\n    }\n\n\n    #fm-hourly-rate-box .fm-hourly-rate-explain {\n\t\tmargin: 30px 0 0 0;\n}\n\n    #fm-hourly-rate-box .fm-hourly-rate-percentiles-text {\n\t\tmargin: 0;\n    }\n\t\n    #fm-hourly-rate-box .fm-daily-rate-rate {\n        font-size: 30px;\n        font-weight: bold;\n    }\n \n\n    #fm-hourly-rate-box .fm-date {\n\t    font-size: 12px;\n\t\tpadding-top: 25px;\n        \n    }\n\n<\/style>\n\n<div id=\"fm-hourly-rate-box\">\n\n    <p class=\"fm-hourly-rate-explain\">Seg\u00fan los datos de <a href=\"\/freelancers-directory.html\">freelancermap<\/a>, los <b>Analista de riesgos<\/b> cobran de media:<\/p>\n\t\n\t<div class=\"fm-hourly-rate-rate\">\n        <span id=\"fm-hourly-rate-number\"><\/span> $\/hora\n    <\/div>\n\n<p class=\"fm-hourly-rate-percentiles-text\">La mayor\u00eda de freelancers en esta \u00e1rea cobran entre <b><span id=\"fm-hourly-rate-percentile25\">33<\/span> y <span id=\"fm-hourly-rate-percentile75\">106<\/span> $\/hora<\/b>.<\/p>\n\n<p class=\"fm-hourly-rate-explain\">Los <b>Analista de riesgos<\/b> trabajando <b>a tiempo completo<\/b> (8 horas\/d\u00eda) cobrar\u00edan:<\/p>\n\n\t<div class=\"fm-daily-rate-rate\">\n            <span id=\"fm-daily-rate-number\"><\/span> $\/d\u00eda\n    <\/div>\n    \n    <div class=\"fm-date\">\n        \u00daltima actualizaci\u00f3n: <span id=\"fm-date-date\"><\/span> \n    <\/div>\n<\/div>\n\n\n\n\n<!--\n    This <script> loads the hourly-rate, daily-rate and date from the server when the page is loaded.\n     It must be placed below the box, ideally at the end of the page (e.g. footer).\n     \n    The server will respond with a formatted number, rounded to full euros.\n-->\n<script>\n    (function(){\n        \/\/ change this\n        const searchPhrase =\"Risk Analyst\";\n\n        \/\/ keep this in sync with the domain you are using\n        const domain = 'www.freelancermap.com';\n\n        \/\/ do not change anything below\n        fetch(`https:\/\/${domain}\/price-index\/webhook?q=${encodeURIComponent(searchPhrase)}`)\n                .then(r => r.json())\n                .then(d => {document.getElementById('fm-hourly-rate-number').innerHTML = d.hourly;\n                            document.getElementById('fm-daily-rate-number').innerHTML = d.hourly*8;\n                            document.getElementById('fm-hourly-rate-percentile25').innerHTML = d.percentiles[\"25.0\"].toFixed(0);\n                            document.getElementById('fm-hourly-rate-percentile75').innerHTML = d.percentiles[\"75.0\"].toFixed(0);\n                            document.getElementById('fm-date-date').innerHTML = (new Date()).toLocaleDateString()\n                            });\n                }())\n<\/script>\n\n\n\n\n<h2 class=\"wp-block-heading\">Otros perfiles profesionales:<\/h2>\n\n\n\n\n<ul class=\"su-posts su-posts-list-loop \">\n\n\t\t\t\t\t\t\n\t\t\t\n\t\t\t<li id=\"su-post-32066\" class=\"su-post \">\n\t\t\t\t<a href=\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-scrum-master\/\">\u00bfQu\u00e9 hace un Scrum Master?<\/a>\n\t\t\t<\/li>\n\n\t\t\t\t\t\n\t\t\t\n\t\t\t<li id=\"su-post-29866\" class=\"su-post \">\n\t\t\t\t<a href=\"https:\/\/www.freelancermap.com\/blog\/es\/gerente-financiero\/\">\u00bfQu\u00e9 hace un gerente financiero?<\/a>\n\t\t\t<\/li>\n\n\t\t\t\t\t\n\t\t\t\n\t\t\t<li id=\"su-post-24630\" class=\"su-post \">\n\t\t\t\t<a href=\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-controlador-de-proyectos\/\">\u00bfQu\u00e9 hace un controlador de proyectos o controller?<\/a>\n\t\t\t<\/li>\n\n\t\t\t\t\t\n\t\t\t\n\t\t\t<li id=\"su-post-40317\" class=\"su-post \">\n\t\t\t\t<a href=\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-director-de-operaciones-coo\/\">\u00bfQu\u00e9 hace un Director de Operaciones (COO)?<\/a>\n\t\t\t<\/li>\n\n\t\t\t\t\t\n\t\t\t\n\t\t\t<li id=\"su-post-32531\" class=\"su-post \">\n\t\t\t\t<a href=\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-consultor-sas\/\">\u00bfQu\u00e9 hace un consultor SAS?<\/a>\n\t\t\t<\/li>\n\n\t\t\t\n<\/ul>\n\n\n\n\n<p>  \u00bb <a href=\"https:\/\/www.freelancermap.com\/blog\/es\/perfiles-it-freelance\/#perfiles-consultoria-management\">M\u00e1s perfiles en <em>Consultor\u00eda y Managemen<\/em>t<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los analistas de riesgos son los responsables de identificar las oportunidades y amenazas para una organizaci\u00f3n, en m\u00faltiples \u00e1mbitos de aplicaci\u00f3n. \u00bfC\u00f3mo es su trabajo?<\/p>\n","protected":false},"author":3121,"featured_media":26083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"categories":[4005,3013],"tags":[3415,3421],"class_list":["post-26045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consultoria","category-carrera","tag-perfiles-profesionales","tag-puestos-trabajo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 hace un Analista de Riesgos? | Perfiles en IT | Carrera<\/title>\n<meta name=\"description\" content=\"\u2713 Perfil analista de riesgos en seguridad: Funciones y Conocimientos \u2713 Formaci\u00f3n \u2713 Sueldo \u2794 \u00bfQu\u00e9 necesitas para ser analista de riesgos?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 hace un Analista de Riesgos? | Perfiles en IT | Carrera\" \/>\n<meta property=\"og:description\" content=\"\u2713 Perfil analista de riesgos en seguridad: Funciones y Conocimientos \u2713 Formaci\u00f3n \u2713 Sueldo \u2794 \u00bfQu\u00e9 necesitas para ser analista de riesgos?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/\" \/>\n<meta property=\"og:site_name\" content=\"Freelancer Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/freelancermapInternational\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T06:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T07:34:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yker Valerio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@freelancer_INT\" \/>\n<meta name=\"twitter:site\" content=\"@freelancer_INT\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yker Valerio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/\"},\"author\":{\"name\":\"Yker Valerio\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#\/schema\/person\/34a320a5bca08abdbf5be7ceb445f1fb\"},\"headline\":\"\u00bfQu\u00e9 hace un Analista de Riesgos?\",\"datePublished\":\"2023-03-27T06:30:00+00:00\",\"dateModified\":\"2023-06-07T07:34:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/\"},\"wordCount\":1666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png\",\"keywords\":[\"Perfiles profesionales\",\"Puesto de trabajo\"],\"articleSection\":[\"Consultor\u00eda y gesti\u00f3n\",\"Trabajo &amp; Carrera\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/\",\"url\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/\",\"name\":\"\u00bfQu\u00e9 hace un Analista de Riesgos? | Perfiles en IT | Carrera\",\"isPartOf\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png\",\"datePublished\":\"2023-03-27T06:30:00+00:00\",\"dateModified\":\"2023-06-07T07:34:23+00:00\",\"description\":\"\u2713 Perfil analista de riesgos en seguridad: Funciones y Conocimientos \u2713 Formaci\u00f3n \u2713 Sueldo \u2794 \u00bfQu\u00e9 necesitas para ser analista de riesgos?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage\",\"url\":\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png\",\"contentUrl\":\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png\",\"width\":650,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.freelancermap.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 hace un Analista de Riesgos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#website\",\"url\":\"https:\/\/www.freelancermap.com\/blog\/\",\"name\":\"Freelancer Blog\",\"description\":\"Tips &amp; Practical Advice for Freelancers and IT professionals\",\"publisher\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.freelancermap.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#organization\",\"name\":\"freelancermap.com\",\"url\":\"https:\/\/www.freelancermap.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2025\/02\/freelancermap-black-logo@4x.png\",\"contentUrl\":\"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2025\/02\/freelancermap-black-logo@4x.png\",\"width\":1044,\"height\":145,\"caption\":\"freelancermap.com\"},\"image\":{\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/freelancermapInternational\/\",\"https:\/\/x.com\/freelancer_INT\",\"https:\/\/www.linkedin.com\/company\/freelancermap-gmbh\/\",\"https:\/\/www.instagram.com\/freelancermap_int\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#\/schema\/person\/34a320a5bca08abdbf5be7ceb445f1fb\",\"name\":\"Yker Valerio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.freelancermap.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b45091d38d64ce673c6d27515c504158?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b45091d38d64ce673c6d27515c504158?s=96&d=mm&r=g\",\"caption\":\"Yker Valerio\"},\"url\":\"https:\/\/www.freelancermap.com\/blog\/author\/yker-valerio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 hace un Analista de Riesgos? | Perfiles en IT | Carrera","description":"\u2713 Perfil analista de riesgos en seguridad: Funciones y Conocimientos \u2713 Formaci\u00f3n \u2713 Sueldo \u2794 \u00bfQu\u00e9 necesitas para ser analista de riesgos?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfQu\u00e9 hace un Analista de Riesgos? | Perfiles en IT | Carrera","og_description":"\u2713 Perfil analista de riesgos en seguridad: Funciones y Conocimientos \u2713 Formaci\u00f3n \u2713 Sueldo \u2794 \u00bfQu\u00e9 necesitas para ser analista de riesgos?","og_url":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/","og_site_name":"Freelancer Blog","article_publisher":"https:\/\/www.facebook.com\/freelancermapInternational\/","article_published_time":"2023-03-27T06:30:00+00:00","article_modified_time":"2023-06-07T07:34:23+00:00","og_image":[{"width":650,"height":500,"url":"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png","type":"image\/png"}],"author":"Yker Valerio","twitter_card":"summary_large_image","twitter_creator":"@freelancer_INT","twitter_site":"@freelancer_INT","twitter_misc":{"Written by":"Yker Valerio","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#article","isPartOf":{"@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/"},"author":{"name":"Yker Valerio","@id":"https:\/\/www.freelancermap.com\/blog\/#\/schema\/person\/34a320a5bca08abdbf5be7ceb445f1fb"},"headline":"\u00bfQu\u00e9 hace un Analista de Riesgos?","datePublished":"2023-03-27T06:30:00+00:00","dateModified":"2023-06-07T07:34:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/"},"wordCount":1666,"commentCount":0,"publisher":{"@id":"https:\/\/www.freelancermap.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png","keywords":["Perfiles profesionales","Puesto de trabajo"],"articleSection":["Consultor\u00eda y gesti\u00f3n","Trabajo &amp; Carrera"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/","url":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/","name":"\u00bfQu\u00e9 hace un Analista de Riesgos? | Perfiles en IT | Carrera","isPartOf":{"@id":"https:\/\/www.freelancermap.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage"},"image":{"@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png","datePublished":"2023-03-27T06:30:00+00:00","dateModified":"2023-06-07T07:34:23+00:00","description":"\u2713 Perfil analista de riesgos en seguridad: Funciones y Conocimientos \u2713 Formaci\u00f3n \u2713 Sueldo \u2794 \u00bfQu\u00e9 necesitas para ser analista de riesgos?","breadcrumb":{"@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#primaryimage","url":"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png","contentUrl":"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png","width":650,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.freelancermap.com\/blog\/es\/que-hace-analista-de-riesgos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freelancermap.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 hace un Analista de Riesgos?"}]},{"@type":"WebSite","@id":"https:\/\/www.freelancermap.com\/blog\/#website","url":"https:\/\/www.freelancermap.com\/blog\/","name":"Freelancer Blog","description":"Tips &amp; Practical Advice for Freelancers and IT professionals","publisher":{"@id":"https:\/\/www.freelancermap.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freelancermap.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.freelancermap.com\/blog\/#organization","name":"freelancermap.com","url":"https:\/\/www.freelancermap.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freelancermap.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2025\/02\/freelancermap-black-logo@4x.png","contentUrl":"https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2025\/02\/freelancermap-black-logo@4x.png","width":1044,"height":145,"caption":"freelancermap.com"},"image":{"@id":"https:\/\/www.freelancermap.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/freelancermapInternational\/","https:\/\/x.com\/freelancer_INT","https:\/\/www.linkedin.com\/company\/freelancermap-gmbh\/","https:\/\/www.instagram.com\/freelancermap_int\/"]},{"@type":"Person","@id":"https:\/\/www.freelancermap.com\/blog\/#\/schema\/person\/34a320a5bca08abdbf5be7ceb445f1fb","name":"Yker Valerio","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freelancermap.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b45091d38d64ce673c6d27515c504158?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b45091d38d64ce673c6d27515c504158?s=96&d=mm&r=g","caption":"Yker Valerio"},"url":"https:\/\/www.freelancermap.com\/blog\/author\/yker-valerio\/"}]}},"taxonomy_info":{"category":[{"value":4005,"label":"Consultor\u00eda y gesti\u00f3n"},{"value":3013,"label":"Trabajo &amp; Carrera"}],"post_tag":[{"value":3415,"label":"Perfiles profesionales"},{"value":3421,"label":"Puesto de trabajo"}]},"featured_image_src_large":["https:\/\/www.freelancermap.com\/blog\/wp-content\/uploads\/2020\/11\/que-hace-analista-de-riesgo.png",650,500,false],"author_info":{"display_name":"Yker Valerio","author_link":"https:\/\/www.freelancermap.com\/blog\/author\/yker-valerio\/"},"comment_info":0,"category_info":[{"term_id":4005,"name":"Consultor\u00eda y gesti\u00f3n","slug":"consultoria","term_group":0,"term_taxonomy_id":4005,"taxonomy":"category","description":"","parent":3013,"count":41,"filter":"raw","cat_ID":4005,"category_count":41,"category_description":"","cat_name":"Consultor\u00eda y gesti\u00f3n","category_nicename":"consultoria","category_parent":3013},{"term_id":3013,"name":"Trabajo &amp; Carrera","slug":"carrera","term_group":0,"term_taxonomy_id":3013,"taxonomy":"category","description":"","parent":0,"count":218,"filter":"raw","cat_ID":3013,"category_count":218,"category_description":"","cat_name":"Trabajo &amp; Carrera","category_nicename":"carrera","category_parent":0}],"tag_info":[{"term_id":3415,"name":"Perfiles profesionales","slug":"perfiles-profesionales","term_group":0,"term_taxonomy_id":3415,"taxonomy":"post_tag","description":"","parent":0,"count":198,"filter":"raw"},{"term_id":3421,"name":"Puesto de trabajo","slug":"puestos-trabajo","term_group":0,"term_taxonomy_id":3421,"taxonomy":"post_tag","description":"","parent":0,"count":198,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/posts\/26045"}],"collection":[{"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/users\/3121"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/comments?post=26045"}],"version-history":[{"count":31,"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/posts\/26045\/revisions"}],"predecessor-version":[{"id":39070,"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/posts\/26045\/revisions\/39070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/media\/26083"}],"wp:attachment":[{"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/media?parent=26045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/categories?post=26045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freelancermap.com\/blog\/wp-json\/wp\/v2\/tags?post=26045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}